{"id":240206,"date":"2026-09-02T14:41:50","date_gmt":"2026-09-02T12:41:50","guid":{"rendered":"https:\/\/www.ilnotiziario.net\/wp\/?p=240206"},"modified":"2026-09-02T14:41:50","modified_gmt":"2026-09-02T12:41:50","slug":"tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno","status":"publish","type":"post","link":"https:\/\/www.ilnotiziario.net\/wp\/prima-pagina\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\/","title":{"rendered":"Tragedia sulla linea Saronno &#8211; Varese, ragazza 18enne morta investita dal treno"},"content":{"rendered":"<p>Tragedia nella tarda mattinata di oggi, mercoled\u00ec 2 settembre, lungo la linea ferroviaria da Varese a Saronno. Una giovane di soli 18 anni ha perso la vita dopo essere stata investita da un convoglio nei pressi della stazione di Tradate Abbiate Guazzone.<\/p><div id=\"ilnot-2997831099\" class=\"ilnot-contenuto ilnot-entity-placement\"><p><!-- incontent_1 --><\/p>\n<div class=\"gptslot\" data-adunitid=\"1\"><\/div>\n<\/div>\n<p>L&#8217;incidente si \u00e8 verificato poco dopo le 12,30 e ha coinvolto il treno regionale 44, partito da Cocquio Trevisago alle 11.53 e diretto alla stazione di Milano Cadorna, dove l&#8217;arrivo era programmato per le 13.09. Immediato l&#8217;allarme lanciato dal personale di bordo e dai presenti. Sul posto si sono precipitati i soccorsi sanitari e le forze dell&#8217;ordine, ma per la giovane non c&#8217;\u00e8 stato nulla da fare: il personale medico non ha potuto fare altro che dichiararne il decesso sul posto a causa delle gravissime lesioni riportate.<\/p>\n<h2>Ragazza morta\u00a0 investita dal treno sulla linea Saronno-Varese, ripercussioni sul traffico ferroviario<\/h2>\n<p>Per consentire i rilievi dell&#8217;autorit\u00e0 giudiziaria e la messa in sicurezza dell&#8217;area, la circolazione dei treni \u00e8 stata inevitabilmente interrotta nel tratto compreso tra le stazioni di Tradate Abbiate Guazzone e Saronno. Trenord ha attivato tempestivamente un servizio di autobus sostitutivi lungo la direttrice interessata per garantire i collegamenti ai pendolari e limitare i disagi.<\/p><div id=\"ilnot-169554188\" class=\"ilnot-contenuto_2 ilnot-entity-placement\"><div class=\"presscom-box\">\r\n    <div class=\"presscom-item\">\r\n        <div id=\"ilnot-4028300373\" style=\"float: right;width: 320px;height: 100px;\"><a data-no-instant=\"1\" href=\"https:\/\/cedamitalia.it\/servizio\/radiologia\/\" rel=\"noopener\" class=\"a2t-link\"><iframe\r\n    src=\"\/wp-content\/uploads\/cedam-banner\/\"\r\n    width=\"320\"\r\n    height=\"100\"\r\n    frameborder=\"0\"\r\n    scrolling=\"no\"\r\n    loading=\"lazy\"\r\n    style=\"border:0;overflow:hidden\">\r\n<\/iframe><\/a><\/div>\r\n    <\/div>\r\n\r\n    <div class=\"presscom-item\">\r\n        <div id=\"ilnot-2941239242\"><div id=\"ilnot-1732950492\" style=\"margin-right: auto;margin-left: auto;text-align: center;width: 320px;height: 100px;\"><a href=\"https:\/\/www.studiobriccaclaudio.com\/\"><img src=\"https:\/\/www.ilnotiziario.net\/wp\/wp-content\/uploads\/2026\/05\/banner-briccaok.gif\" alt=\"Studio Bricca\"><\/a>.<\/div><\/div>\r\n    <\/div>\r\n<\/div><\/div>\n<p>Sono tuttora in corso le indagini da parte delle forze dell&#8217;ordine per ricostruire con esattezza la dinamica dell&#8217;accaduto e chiarire le cause dell&#8217;investimento.<\/p>\n<p><a href=\"https:\/\/www.ilnotiziario.net\/wp\/chi-siamo\/\"><strong>Redazione Online\u00a0<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tragedia nella tarda mattinata di oggi, mercoled\u00ec 2 settembre, lungo la linea ferroviaria da Varese a Saronno. Una giovane di soli 18 anni ha perso la vita dopo essere stata investita da un convoglio nei pressi della stazione di Tradate Abbiate Guazzone. L&#8217;incidente si \u00e8 verificato poco dopo le 12,30 e ha coinvolto il treno<\/p>\n","protected":false},"author":3,"featured_media":238977,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[1168,272,56,35],"class_list":["post-240206","post","type-post","status-publish","format-standard","has-post-thumbnail","category-prima-pagina","tag-investita","tag-morta","tag-saronno-2","tag-treno"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tragedia sulla linea Saronno - Varese, ragazza 18enne morta investita dal treno - Il Notiziario<\/title>\n<meta name=\"description\" content=\"Tragedia nella tarda mattinata di oggi, mercoled\u00ec 2 settembre, lungo la linea ferroviaria da Varese a Saronno. Una giovane di soli 18 anni ha perso la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ilnotiziario.net\/wp\/prima-pagina\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tragedia sulla linea Saronno - Varese, ragazza 18enne morta investita dal treno - Il Notiziario\" \/>\n<meta property=\"og:description\" content=\"Tragedia nella tarda mattinata di oggi, mercoled\u00ec 2 settembre, lungo la linea ferroviaria da Varese a Saronno. Una giovane di soli 18 anni ha perso la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ilnotiziario.net\/wp\/prima-pagina\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\/\" \/>\n<meta property=\"og:site_name\" content=\"Il Notiziario\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ilnotiziarioind\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T12:41:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ilnotiziario.net\/wp\/wp-content\/uploads\/2026\/08\/immagine-di-repertorio-2026-08-07T072616.574.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriele Bassani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ilNotiziarioInd\" \/>\n<meta name=\"twitter:site\" content=\"@ilNotiziarioInd\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriele Bassani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/prima-pagina\\\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/prima-pagina\\\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\\\/\"},\"author\":{\"name\":\"Gabriele Bassani\",\"@id\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/#\\\/schema\\\/person\\\/386e222908f898bb41c033989482bbf2\"},\"headline\":\"Tragedia sulla linea Saronno &#8211; Varese, ragazza 18enne morta investita dal treno\",\"datePublished\":\"2026-09-02T12:41:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/prima-pagina\\\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\\\/\"},\"wordCount\":234,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/prima-pagina\\\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/immagine-di-repertorio-2026-08-07T072616.574.jpg\",\"keywords\":[\"investita\",\"morta\",\"Saronno\",\"treno\"],\"articleSection\":[\"Prima Pagina\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/prima-pagina\\\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\\\/\",\"url\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/prima-pagina\\\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\\\/\",\"name\":\"Tragedia sulla linea Saronno - Varese, ragazza 18enne morta investita dal treno - Il Notiziario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/prima-pagina\\\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/prima-pagina\\\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/immagine-di-repertorio-2026-08-07T072616.574.jpg\",\"datePublished\":\"2026-09-02T12:41:50+00:00\",\"description\":\"Tragedia nella tarda mattinata di oggi, mercoled\u00ec 2 settembre, lungo la linea ferroviaria da Varese a Saronno. Una giovane di soli 18 anni ha perso la\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/prima-pagina\\\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/prima-pagina\\\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/prima-pagina\\\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/immagine-di-repertorio-2026-08-07T072616.574.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/immagine-di-repertorio-2026-08-07T072616.574.jpg\",\"width\":1200,\"height\":630,\"caption\":\"Immagine di repertorio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/prima-pagina\\\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"tds_text_logo_tagline_colortds_text_logo_tagline_colortds_text_logo_tagline_colortds_text_logo_tagline_colortd_module_7_title_excerpttd_module_7_title_excerpttd_module_7_title_excerpttd_module_7_title_excerptHome\",\"item\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tragedia sulla linea Saronno &#8211; Varese, ragazza 18enne morta investita dal treno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/\",\"name\":\"Il Notiziario\",\"description\":\"Per restare sempre connessi alla notizia\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/#organization\"},\"alternateName\":\"Il Notiziario Bollate\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/#organization\",\"name\":\"Il Notiziario\",\"url\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/170x170ilN.png\",\"contentUrl\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/170x170ilN.png\",\"width\":355,\"height\":355,\"caption\":\"Il Notiziario\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ilnotiziarioind\\\/\",\"https:\\\/\\\/x.com\\\/ilNotiziarioInd\",\"https:\\\/\\\/www.instagram.com\\\/ilnotiziario_settimanale\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ilnotiziario.net\\\/wp\\\/#\\\/schema\\\/person\\\/386e222908f898bb41c033989482bbf2\",\"name\":\"Gabriele Bassani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09274f4a84fa97698bde56f84b3afed61c8492d48b0550db9671b68c177479cb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09274f4a84fa97698bde56f84b3afed61c8492d48b0550db9671b68c177479cb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09274f4a84fa97698bde56f84b3afed61c8492d48b0550db9671b68c177479cb?s=96&d=mm&r=g\",\"caption\":\"Gabriele Bassani\"},\"sameAs\":[\"http:\\\/\\\/www.ilnotiziario.net\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tragedia sulla linea Saronno - Varese, ragazza 18enne morta investita dal treno - Il Notiziario","description":"Tragedia nella tarda mattinata di oggi, mercoled\u00ec 2 settembre, lungo la linea ferroviaria da Varese a Saronno. Una giovane di soli 18 anni ha perso la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ilnotiziario.net\/wp\/prima-pagina\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\/","og_locale":"it_IT","og_type":"article","og_title":"Tragedia sulla linea Saronno - Varese, ragazza 18enne morta investita dal treno - Il Notiziario","og_description":"Tragedia nella tarda mattinata di oggi, mercoled\u00ec 2 settembre, lungo la linea ferroviaria da Varese a Saronno. Una giovane di soli 18 anni ha perso la","og_url":"https:\/\/www.ilnotiziario.net\/wp\/prima-pagina\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\/","og_site_name":"Il Notiziario","article_publisher":"https:\/\/www.facebook.com\/ilnotiziarioind\/","article_published_time":"2026-09-02T12:41:50+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.ilnotiziario.net\/wp\/wp-content\/uploads\/2026\/08\/immagine-di-repertorio-2026-08-07T072616.574.jpg","type":"image\/jpeg"}],"author":"Gabriele Bassani","twitter_card":"summary_large_image","twitter_creator":"@ilNotiziarioInd","twitter_site":"@ilNotiziarioInd","twitter_misc":{"Scritto da":"Gabriele Bassani","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ilnotiziario.net\/wp\/prima-pagina\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\/#article","isPartOf":{"@id":"https:\/\/www.ilnotiziario.net\/wp\/prima-pagina\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\/"},"author":{"name":"Gabriele Bassani","@id":"https:\/\/www.ilnotiziario.net\/wp\/#\/schema\/person\/386e222908f898bb41c033989482bbf2"},"headline":"Tragedia sulla linea Saronno &#8211; Varese, ragazza 18enne morta investita dal treno","datePublished":"2026-09-02T12:41:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ilnotiziario.net\/wp\/prima-pagina\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\/"},"wordCount":234,"publisher":{"@id":"https:\/\/www.ilnotiziario.net\/wp\/#organization"},"image":{"@id":"https:\/\/www.ilnotiziario.net\/wp\/prima-pagina\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ilnotiziario.net\/wp\/wp-content\/uploads\/2026\/08\/immagine-di-repertorio-2026-08-07T072616.574.jpg","keywords":["investita","morta","Saronno","treno"],"articleSection":["Prima Pagina"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.ilnotiziario.net\/wp\/prima-pagina\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\/","url":"https:\/\/www.ilnotiziario.net\/wp\/prima-pagina\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\/","name":"Tragedia sulla linea Saronno - Varese, ragazza 18enne morta investita dal treno - Il Notiziario","isPartOf":{"@id":"https:\/\/www.ilnotiziario.net\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ilnotiziario.net\/wp\/prima-pagina\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\/#primaryimage"},"image":{"@id":"https:\/\/www.ilnotiziario.net\/wp\/prima-pagina\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ilnotiziario.net\/wp\/wp-content\/uploads\/2026\/08\/immagine-di-repertorio-2026-08-07T072616.574.jpg","datePublished":"2026-09-02T12:41:50+00:00","description":"Tragedia nella tarda mattinata di oggi, mercoled\u00ec 2 settembre, lungo la linea ferroviaria da Varese a Saronno. Una giovane di soli 18 anni ha perso la","breadcrumb":{"@id":"https:\/\/www.ilnotiziario.net\/wp\/prima-pagina\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ilnotiziario.net\/wp\/prima-pagina\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ilnotiziario.net\/wp\/prima-pagina\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\/#primaryimage","url":"https:\/\/www.ilnotiziario.net\/wp\/wp-content\/uploads\/2026\/08\/immagine-di-repertorio-2026-08-07T072616.574.jpg","contentUrl":"https:\/\/www.ilnotiziario.net\/wp\/wp-content\/uploads\/2026\/08\/immagine-di-repertorio-2026-08-07T072616.574.jpg","width":1200,"height":630,"caption":"Immagine di repertorio"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ilnotiziario.net\/wp\/prima-pagina\/tragedia-sulla-linea-saronno-varese-ragazza-18enne-morta-investita-dal-treno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"tds_text_logo_tagline_colortds_text_logo_tagline_colortds_text_logo_tagline_colortds_text_logo_tagline_colortd_module_7_title_excerpttd_module_7_title_excerpttd_module_7_title_excerpttd_module_7_title_excerptHome","item":"https:\/\/www.ilnotiziario.net\/wp\/"},{"@type":"ListItem","position":2,"name":"Tragedia sulla linea Saronno &#8211; Varese, ragazza 18enne morta investita dal treno"}]},{"@type":"WebSite","@id":"https:\/\/www.ilnotiziario.net\/wp\/#website","url":"https:\/\/www.ilnotiziario.net\/wp\/","name":"Il Notiziario","description":"Per restare sempre connessi alla notizia","publisher":{"@id":"https:\/\/www.ilnotiziario.net\/wp\/#organization"},"alternateName":"Il Notiziario Bollate","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ilnotiziario.net\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.ilnotiziario.net\/wp\/#organization","name":"Il Notiziario","url":"https:\/\/www.ilnotiziario.net\/wp\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ilnotiziario.net\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/www.ilnotiziario.net\/wp\/wp-content\/uploads\/2022\/06\/170x170ilN.png","contentUrl":"https:\/\/www.ilnotiziario.net\/wp\/wp-content\/uploads\/2022\/06\/170x170ilN.png","width":355,"height":355,"caption":"Il Notiziario"},"image":{"@id":"https:\/\/www.ilnotiziario.net\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ilnotiziarioind\/","https:\/\/x.com\/ilNotiziarioInd","https:\/\/www.instagram.com\/ilnotiziario_settimanale\/"]},{"@type":"Person","@id":"https:\/\/www.ilnotiziario.net\/wp\/#\/schema\/person\/386e222908f898bb41c033989482bbf2","name":"Gabriele Bassani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/09274f4a84fa97698bde56f84b3afed61c8492d48b0550db9671b68c177479cb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/09274f4a84fa97698bde56f84b3afed61c8492d48b0550db9671b68c177479cb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/09274f4a84fa97698bde56f84b3afed61c8492d48b0550db9671b68c177479cb?s=96&d=mm&r=g","caption":"Gabriele Bassani"},"sameAs":["http:\/\/www.ilnotiziario.net"]}]}},"_links":{"self":[{"href":"https:\/\/www.ilnotiziario.net\/wp\/wp-json\/wp\/v2\/posts\/240206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ilnotiziario.net\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilnotiziario.net\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilnotiziario.net\/wp\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilnotiziario.net\/wp\/wp-json\/wp\/v2\/comments?post=240206"}],"version-history":[{"count":1,"href":"https:\/\/www.ilnotiziario.net\/wp\/wp-json\/wp\/v2\/posts\/240206\/revisions"}],"predecessor-version":[{"id":240207,"href":"https:\/\/www.ilnotiziario.net\/wp\/wp-json\/wp\/v2\/posts\/240206\/revisions\/240207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilnotiziario.net\/wp\/wp-json\/wp\/v2\/media\/238977"}],"wp:attachment":[{"href":"https:\/\/www.ilnotiziario.net\/wp\/wp-json\/wp\/v2\/media?parent=240206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilnotiziario.net\/wp\/wp-json\/wp\/v2\/categories?post=240206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilnotiziario.net\/wp\/wp-json\/wp\/v2\/tags?post=240206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}